{"id":7100,"date":"2025-04-14T10:00:00","date_gmt":"2025-04-14T08:00:00","guid":{"rendered":"https:\/\/manther.de\/?p=7100"},"modified":"2025-03-31T11:35:39","modified_gmt":"2025-03-31T09:35:39","slug":"benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers","status":"publish","type":"post","link":"https:\/\/manther.de\/fr\/2025\/04\/la-representation-poetique-et-explicite-du-corps-humain\/","title":{"rendered":"D\u00e9nomination des parties du corps: la repr\u00e9sentation po\u00e9tique et explicite du corps humain"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La litt\u00e9rature \u00e9rotique a connu une transformation remarquable dans sa repr\u00e9sentation du corps humain. Cette \u00e9volution refl\u00e8te non seulement des pr\u00e9f\u00e9rences esth\u00e9tiques, mais aussi des changements sociaux profonds dans la fa\u00e7on dont la sexualit\u00e9 et la corporalit\u00e9 sont abord\u00e9es. Aujourd&#8217;hui, \u00e9crivains et lecteurs sont confront\u00e9s au d\u00e9fi de trouver un langage \u00e0 la fois pr\u00e9cis et po\u00e9tique, qui ne dissimule pas le corps et ne le met pas non plus \u00e0 nu de mani\u00e8re vulgaire.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-evolution-historique-du-voile-a-la-precision\">\u00c9volution historique : du voile \u00e0 la pr\u00e9cision<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les premi\u00e8res \u0153uvres \u00e9rotiques se contentaient principalement d&#8217;allusions et de m\u00e9taphores. Au XVIIIe si\u00e8cle, dans des \u0153uvres telles que \u00abFanny Hill\u00bb (1748) de John Cleland, les organes g\u00e9nitaux \u00e9taient constamment d\u00e9crits de mani\u00e8re indirecte : les organes sexuels masculins apparaissaient sous la forme d&#8217;un \u00abb\u00e2ton\u00bb ou d&#8217;un \u00abm\u00e2t\u00bb, les organes f\u00e9minins sous la forme d&#8217;une \u00abgrotte\u00bb ou d&#8217;un \u00abcoffret \u00e0 bijoux\u00bb. Ces euph\u00e9mismes remplissaient une double fonction : ils contournaient la censure tout en conservant une distance po\u00e9tique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le XIXe si\u00e8cle, avec sa pruderie victorienne, a renforc\u00e9 cette tendance \u00e0 la dissimulation. Le corps disparaissait derri\u00e8re des ellipses et des allusions vagues. L&#8217;\u00e9rotisme r\u00e9sidait dans le non-dit, dans les tirets et les pauses significatives.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le changement d\u00e9cisif a commenc\u00e9 au d\u00e9but du XXe si\u00e8cle avec des auteurs tels que D.H. Lawrence, dont \u00abL&#8217;amant de Lady Chatterley\u00bb (1928) alliait clart\u00e9 anatomique et sensibilit\u00e9 po\u00e9tique. Lawrence osait nommer directement les parties du corps sans tomber dans la st\u00e9rilit\u00e9 clinique: \u00abElle sentit la pointe douce de son p\u00e9nis qui la touchait\u00bb. Cette nouvelle franchise a suscit\u00e9 la controverse, mais a marqu\u00e9 un changement de paradigme important.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-revolution-feministe-le-corps-comme-terrain-politique\">La r\u00e9volution f\u00e9ministe : le corps comme terrain politique<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le mouvement f\u00e9ministe des ann\u00e9es 1960 et 1970 a catalys\u00e9 un changement fondamental dans la repr\u00e9sentation litt\u00e9raire du corps f\u00e9minin. Des autrices telles qu&#8217;Ana\u00efs Nin, Erica Jong et plus tard Audre Lorde ont compris que nommer les parties du corps f\u00e9minin \u00e9tait un acte d&#8217;autonomisation. Le vagin, la vulve, le clitoris : ce qui n&#8217;est pas nomm\u00e9 n&#8217;existe pas pleinement dans la conscience culturelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans l&#8217;\u0153uvre r\u00e9volutionnaire d&#8217;Erica Jong, \u00ab Fear of Flying \u00bb (1973), le personnage principal exprime ses d\u00e9sirs sexuels avec une franchise jusque-l\u00e0 inou\u00efe : \u00ab Je voulais qu&#8217;il caresse mon clitoris, pas mon ego. \u00bb Cette pr\u00e9cision anatomique \u00e9tait r\u00e9volutionnaire : elle d\u00e9pla\u00e7ait l&#8217;attention du corps masculin vers le corps f\u00e9minin et ses sources de plaisir autonomes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La critique f\u00e9ministe a \u00e9galement mis en \u00e9vidence le langage asym\u00e9trique de la litt\u00e9rature \u00e9rotique traditionnelle : alors que les organes g\u00e9nitaux masculins \u00e9taient souvent associ\u00e9s \u00e0 l&#8217;activit\u00e9 et au pouvoir (\u00ab il la p\u00e9n\u00e9tra \u00bb), les organes g\u00e9nitaux f\u00e9minins \u00e9taient pr\u00e9sent\u00e9s comme des r\u00e9cepteurs passifs (\u00ab elle le re\u00e7ut \u00bb). Ces sch\u00e9mas linguistiques reproduisaient des relations de genre probl\u00e9matiques. Les auteures f\u00e9ministes ont d\u00e9velopp\u00e9 un nouveau langage qui mettait en avant l&#8217;activit\u00e9 sexuelle et le pouvoir d&#8217;action des femmes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-l-equilibre-contemporain-precision-et-poesie\">L&#8217;\u00e9quilibre contemporain : pr\u00e9cision et po\u00e9sie<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La litt\u00e9rature \u00e9rotique contemporaine a d\u00e9velopp\u00e9 un \u00e9quilibre nuanc\u00e9. Des auteurs tels que Lisa Taddeo (Three Women, 2019) ou Garth Greenwell (What Belongs to You, 2016) combinent une pr\u00e9cision anatomique avec une sensibilit\u00e9 esth\u00e9tique. Ils nomment directement les parties du corps sans tomber dans les extr\u00eames d&#8217;un langage clinique ou vulgaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un exemple r\u00e9ussi pourrait \u00eatre : \u00ab Le bout de ses doigts glissa sur ses l\u00e8vres, qui s&#8217;ouvrirent sous son toucher comme une fleur dans la lumi\u00e8re du matin. \u00bb Ici, la clart\u00e9 anatomique (\u00ab l\u00e8vres \u00bb) se combine avec un langage imag\u00e9 po\u00e9tique (\u00ab comme une fleur \u00bb), sans pour autant tomber dans une vague euph\u00e9misation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette \u00e9volution t\u00e9moigne d&#8217;un progr\u00e8s psychologique important : nous avons appris que le corps n&#8217;est ni honteux ni purement fonctionnel. Il m\u00e9rite un langage qui reconnaisse \u00e0 la fois sa r\u00e9alit\u00e9 biologique et sa dimension \u00e9motionnelle et esth\u00e9tique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-dimension-psychologique-du-langage-corporel\">La dimension psychologique du langage corporel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La fa\u00e7on dont nous d\u00e9signons les parties du corps dans la litt\u00e9rature \u00e9rotique influence de mani\u00e8re significative l&#8217;effet psychologique du texte. Trois dimensions sont particuli\u00e8rement pertinentes \u00e0 cet \u00e9gard :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Intimit\u00e9 vs distance<\/strong> : la terminologie m\u00e9dicale (\u00ab vagin \u00bb, \u00ab p\u00e9nis \u00bb) cr\u00e9e une distance \u00e9motionnelle, tandis que les expressions famili\u00e8res ou vulgaires sugg\u00e8rent souvent une proximit\u00e9, mais aussi une objectivation. Le d\u00e9fi consiste \u00e0 trouver un langage qui permette l&#8217;intimit\u00e9 sans objectiver.<\/li>\n\n\n\n<li><strong>Subjectivit\u00e9 vs objectivit\u00e9<\/strong> : la litt\u00e9rature \u00e9rotique traditionnelle d\u00e9crit souvent le corps d&#8217;un point de vue ext\u00e9rieur objectivant. Les auteurs contemporains se concentrent de plus en plus sur l&#8217;exp\u00e9rience subjective du corps : quelle sensation procure un toucher ? Quelles r\u00e9actions \u00e9motionnelles d\u00e9clenche-t-il ?<\/li>\n\n\n\n<li><strong>Pouvoir et vuln\u00e9rabilit\u00e9<\/strong> : la d\u00e9nomination des parties du corps soul\u00e8ve in\u00e9vitablement des questions de pouvoir et de vuln\u00e9rabilit\u00e9. Un langage \u00e9rotique sensible refl\u00e8te cette dynamique sans l&#8217;exploiter.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-limites-et-libertes-au-xxie-siecle\">Limites et libert\u00e9s au XXIe si\u00e8cle<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il n&#8217;y a pas de r\u00e9ponse universelle \u00e0 la question de savoir jusqu&#8217;o\u00f9 peut aller la litt\u00e9rature \u00e9rotique aujourd&#8217;hui. Dans la plupart des soci\u00e9t\u00e9s occidentales, les limites l\u00e9gales sont tr\u00e8s larges. Les v\u00e9ritables limites sont d\u00e9finies par des consid\u00e9rations esth\u00e9tiques, \u00e9thiques et psychologiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce n&#8217;est pas le degr\u00e9 d&#8217;explicite qui est d\u00e9terminant, mais l&#8217;attitude et l&#8217;intention. Des descriptions explicites qui repr\u00e9sentent le corps avec respect et reconnaissent sa complexit\u00e9 peuvent produire une profonde r\u00e9sonance esth\u00e9tique et \u00e9motionnelle. De m\u00eame, des repr\u00e9sentations pr\u00e9tendument \u00ab douces \u00bb peuvent \u00eatre probl\u00e9matiques si elles objectivent ou st\u00e9r\u00e9otypent le corps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tant qu&#8217;auteurs et lecteurs, nous sommes confront\u00e9s au d\u00e9fi de d\u00e9velopper un langage qui combine les qualit\u00e9s suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Pr\u00e9cision sans froideur clinique<\/strong> : le corps est plus que la somme de ses parties anatomiques.<\/li>\n\n\n\n<li><strong>Po\u00e9sie sans euph\u00e9mismes voilants<\/strong> : les m\u00e9taphores ne doivent pas dissimuler la r\u00e9alit\u00e9 physique, mais l&#8217;approfondir.<\/li>\n\n\n\n<li><strong>Respect sans prudeur<\/strong> : une repr\u00e9sentation respectueuse ne signifie pas \u00e9viter l&#8217;explicite.<\/li>\n\n\n\n<li><strong>La passion sans objectivation<\/strong> : les corps ne sont pas des objets, mais des entit\u00e9s vivantes et sensibles.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusion-le-corps-detabouise-comme-defi-litteraire\">Conclusion : le corps d\u00e9tabouis\u00e9 comme d\u00e9fi litt\u00e9raire<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;\u00e9volution de la litt\u00e9rature \u00e9rotique montre une voie progressive vers la d\u00e9tabouisation du corps. Nous avons appris que le corps humain n&#8217;est ni honteux ni obsc\u00e8ne &#8211; il m\u00e9rite un langage qui reconnaisse \u00e0 la fois sa r\u00e9alit\u00e9 biologique et sa dimension \u00e9motionnelle et esth\u00e9tique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La litt\u00e9rature \u00e9rotique la plus r\u00e9ussie de notre \u00e9poque trouve une expression qui ne d\u00e9shonore ni ne mystifie le corps. Elle nomme le corps de mani\u00e8re claire et pr\u00e9cise, sans n\u00e9gliger sa dimension po\u00e9tique et \u00e9motionnelle. Elle reconna\u00eet que chaque corps est unique et que chaque rencontre physique repr\u00e9sente une intrication complexe de physiologie, de psychologie et de dynamique interpersonnelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#8217;est dans cet \u00e9quilibre entre clart\u00e9 anatomique et sensibilit\u00e9 po\u00e9tique que r\u00e9side l&#8217;avenir d&#8217;une litt\u00e9rature \u00e9rotique qui nous permet d&#8217;explorer et de c\u00e9l\u00e9brer le corps dans toute sa complexit\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La litt\u00e9rature \u00e9rotique a connu une transformation remarquable dans sa repr\u00e9sentation du corps humain. Cette \u00e9volution refl\u00e8te non seulement des pr\u00e9f\u00e9rences esth\u00e9tiques, mais aussi des changements sociaux profonds dans la fa\u00e7on dont la sexualit\u00e9 et la corporalit\u00e9 sont abord\u00e9es. Aujourd&#8217;hui, \u00e9crivains et lecteurs sont confront\u00e9s au d\u00e9fi de trouver un langage \u00e0 la fois pr\u00e9cis &hellip; <a href=\"https:\/\/manther.de\/fr\/2025\/04\/la-representation-poetique-et-explicite-du-corps-humain\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">D\u00e9nomination des parties du corps: la repr\u00e9sentation po\u00e9tique et explicite du corps humain<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":7101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[3,10],"tags":[],"class_list":["post-7100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erotika-schreiben","category-koerper"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["de","en","fr"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00e9nomination des parties du corps: la repr\u00e9sentation po\u00e9tique et explicite du corps humain - manther<\/title>\n<meta name=\"description\" content=\"L&#039;\u00e9volution de la repr\u00e9sentation du corps dans la litt\u00e9rature \u00e9rotique du XVIIIe si\u00e8cle \u00e0 nos jours. Un langage anatomique pr\u00e9cis et une sensibilit\u00e9 po\u00e9tique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9nomination des parties du corps: la repr\u00e9sentation po\u00e9tique et explicite du corps humain - manther\" \/>\n<meta property=\"og:description\" content=\"L&#039;\u00e9volution de la repr\u00e9sentation du corps dans la litt\u00e9rature \u00e9rotique du XVIIIe si\u00e8cle \u00e0 nos jours. Un langage anatomique pr\u00e9cis et une sensibilit\u00e9 po\u00e9tique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/\" \/>\n<meta property=\"og:site_name\" content=\"manther\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mantherhh\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-14T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/reading.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"672\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ennka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sandra_Manther\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ennka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/\"},\"author\":{\"name\":\"Ennka\",\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/f1e1c8775b15c7ee7a684f857868d1f1\"},\"headline\":\"D\u00e9nomination des parties du corps: la repr\u00e9sentation po\u00e9tique et explicite du corps humain\",\"datePublished\":\"2025-04-14T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/\"},\"wordCount\":3234,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/5d0a51ad8607f193a3e54080c7286894\"},\"image\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/reading.jpg\",\"articleSection\":[\"\u00c9crire \u00e9rotique\",\"Le corps\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/\",\"url\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/\",\"name\":\"D\u00e9nomination des parties du corps: la repr\u00e9sentation po\u00e9tique et explicite du corps humain - manther\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/reading.jpg\",\"datePublished\":\"2025-04-14T08:00:00+00:00\",\"description\":\"L'\u00e9volution de la repr\u00e9sentation du corps dans la litt\u00e9rature \u00e9rotique du XVIIIe si\u00e8cle \u00e0 nos jours. Un langage anatomique pr\u00e9cis et une sensibilit\u00e9 po\u00e9tique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/reading.jpg\",\"contentUrl\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/reading.jpg\",\"width\":672,\"height\":372,\"caption\":\"eine junge Frau sitzt auf ihrem Bett und liest\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/04\\\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/manther.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Benennen von K\u00f6rperteilen: Die poetische und explizite Darstellung des menschlichen K\u00f6rpers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manther.de\\\/#website\",\"url\":\"https:\\\/\\\/manther.de\\\/\",\"name\":\"manther\",\"description\":\"le magazine de Creative Writing pour la litt\u00e9rature \u00e9rotique\",\"publisher\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/5d0a51ad8607f193a3e54080c7286894\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manther.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/5d0a51ad8607f193a3e54080c7286894\",\"name\":\"Sandra Manther\",\"logo\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"description\":\"Geboren 1981 in Krefeld. Studierte Mediendesign an der hdpk Berlin. Der Liebe wegen ging sie nach Hamburg, wo sie heute als Webdesgnerin in einer bekannten Werbeagentur arbeitet. Sie lebt mit ihrem Mann Marc und den Katzen Mandu und Tharsis in einem Haus im Westen der Stadt.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mantherhh\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/sandramanther\\\/\",\"https:\\\/\\\/x.com\\\/Sandra_Manther\",\"https:\\\/\\\/www.tumblr.com\\\/gamma-xi-delta\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/f1e1c8775b15c7ee7a684f857868d1f1\",\"name\":\"Ennka\",\"sameAs\":[\"http:\\\/\\\/www.norbert-krueger.com\"],\"url\":\"https:\\\/\\\/manther.de\\\/fr\\\/author\\\/ennka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9nomination des parties du corps: la repr\u00e9sentation po\u00e9tique et explicite du corps humain - manther","description":"L'\u00e9volution de la repr\u00e9sentation du corps dans la litt\u00e9rature \u00e9rotique du XVIIIe si\u00e8cle \u00e0 nos jours. Un langage anatomique pr\u00e9cis et une sensibilit\u00e9 po\u00e9tique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9nomination des parties du corps: la repr\u00e9sentation po\u00e9tique et explicite du corps humain - manther","og_description":"L'\u00e9volution de la repr\u00e9sentation du corps dans la litt\u00e9rature \u00e9rotique du XVIIIe si\u00e8cle \u00e0 nos jours. Un langage anatomique pr\u00e9cis et une sensibilit\u00e9 po\u00e9tique.","og_url":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/","og_site_name":"manther","article_publisher":"https:\/\/www.facebook.com\/mantherhh\/","article_published_time":"2025-04-14T08:00:00+00:00","og_image":[{"width":672,"height":372,"url":"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/reading.jpg","type":"image\/jpeg"}],"author":"Ennka","twitter_card":"summary_large_image","twitter_site":"@Sandra_Manther","twitter_misc":{"\u00c9crit par":"Ennka","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/#article","isPartOf":{"@id":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/"},"author":{"name":"Ennka","@id":"https:\/\/manther.de\/#\/schema\/person\/f1e1c8775b15c7ee7a684f857868d1f1"},"headline":"D\u00e9nomination des parties du corps: la repr\u00e9sentation po\u00e9tique et explicite du corps humain","datePublished":"2025-04-14T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/"},"wordCount":3234,"commentCount":0,"publisher":{"@id":"https:\/\/manther.de\/#\/schema\/person\/5d0a51ad8607f193a3e54080c7286894"},"image":{"@id":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/#primaryimage"},"thumbnailUrl":"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/reading.jpg","articleSection":["\u00c9crire \u00e9rotique","Le corps"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/","url":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/","name":"D\u00e9nomination des parties du corps: la repr\u00e9sentation po\u00e9tique et explicite du corps humain - manther","isPartOf":{"@id":"https:\/\/manther.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/#primaryimage"},"image":{"@id":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/#primaryimage"},"thumbnailUrl":"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/reading.jpg","datePublished":"2025-04-14T08:00:00+00:00","description":"L'\u00e9volution de la repr\u00e9sentation du corps dans la litt\u00e9rature \u00e9rotique du XVIIIe si\u00e8cle \u00e0 nos jours. Un langage anatomique pr\u00e9cis et une sensibilit\u00e9 po\u00e9tique.","breadcrumb":{"@id":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/#primaryimage","url":"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/reading.jpg","contentUrl":"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/reading.jpg","width":672,"height":372,"caption":"eine junge Frau sitzt auf ihrem Bett und liest"},{"@type":"BreadcrumbList","@id":"https:\/\/manther.de\/2025\/04\/benennen-von-koerperteilen-die-poetische-und-explizite-darstellung-des-menschlichen-koerpers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/manther.de\/"},{"@type":"ListItem","position":2,"name":"Benennen von K\u00f6rperteilen: Die poetische und explizite Darstellung des menschlichen K\u00f6rpers"}]},{"@type":"WebSite","@id":"https:\/\/manther.de\/#website","url":"https:\/\/manther.de\/","name":"manther","description":"le magazine de Creative Writing pour la litt\u00e9rature \u00e9rotique","publisher":{"@id":"https:\/\/manther.de\/#\/schema\/person\/5d0a51ad8607f193a3e54080c7286894"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manther.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/manther.de\/#\/schema\/person\/5d0a51ad8607f193a3e54080c7286894","name":"Sandra Manther","logo":{"@id":"https:\/\/manther.de\/#\/schema\/person\/image\/"},"description":"Geboren 1981 in Krefeld. Studierte Mediendesign an der hdpk Berlin. Der Liebe wegen ging sie nach Hamburg, wo sie heute als Webdesgnerin in einer bekannten Werbeagentur arbeitet. Sie lebt mit ihrem Mann Marc und den Katzen Mandu und Tharsis in einem Haus im Westen der Stadt.","sameAs":["https:\/\/www.facebook.com\/mantherhh\/","https:\/\/www.pinterest.de\/sandramanther\/","https:\/\/x.com\/Sandra_Manther","https:\/\/www.tumblr.com\/gamma-xi-delta"]},{"@type":"Person","@id":"https:\/\/manther.de\/#\/schema\/person\/f1e1c8775b15c7ee7a684f857868d1f1","name":"Ennka","sameAs":["http:\/\/www.norbert-krueger.com"],"url":"https:\/\/manther.de\/fr\/author\/ennka\/"}]}},"_links":{"self":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts\/7100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/comments?post=7100"}],"version-history":[{"count":3,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts\/7100\/revisions"}],"predecessor-version":[{"id":7106,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts\/7100\/revisions\/7106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/media\/7101"}],"wp:attachment":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/media?parent=7100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/categories?post=7100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/tags?post=7100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}