{"id":7019,"date":"2025-03-27T10:00:00","date_gmt":"2025-03-27T08:00:00","guid":{"rendered":"https:\/\/manther.de\/?p=7019"},"modified":"2025-03-23T18:29:07","modified_gmt":"2025-03-23T16:29:07","slug":"carmen-maria-machado-wenn-erotik-auf-horror-trifft","status":"publish","type":"post","link":"https:\/\/manther.de\/fr\/2025\/03\/carmen-maria-machado-quand-lerotisme-rencontre-lhorreur\/","title":{"rendered":"Carmen Maria Machado : Quand l&#8217;\u00e9rotisme rencontre l&#8217;horreur \u2013 Une r\u00e9volution pour la litt\u00e9rature \u00e9rotique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>As-tu d\u00e9j\u00e0 lu un livre qui t&#8217;excite et te fait frissonner en m\u00eame temps ? Un livre qui brouille les fronti\u00e8res de ton corps et te demande : Qu&#8217;est-ce qui est r\u00e9el ? Qu&#8217;est-ce qui est possible ? Et surtout : \u00c0 qui appartient vraiment ton corps ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carmen Maria Machado, avec son recueil de nouvelles <strong>&#8220;Son corps et autres c\u00e9l\u00e9brations&#8221;<\/strong> (2017), a cr\u00e9\u00e9 exactement ces espaces. Des espaces o\u00f9 l&#8217;\u00e9rotisme queer rencontre l&#8217;inqui\u00e9tant et o\u00f9 nos conceptions du d\u00e9sir, de la corporalit\u00e9 et de l&#8217;identit\u00e9 sont radicalement repens\u00e9es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-magie-de-l-indicible\">La magie de l&#8217;indicible<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ce qui rend Machado si sp\u00e9ciale : elle exprime l&#8217;indicible. Dans une soci\u00e9t\u00e9 qui marginalise encore les corps queer et le d\u00e9sir queer, elle cr\u00e9e un espace pour nos v\u00e9rit\u00e9s sexuelles complexes, contradictoires, parfois m\u00eame d\u00e9rangeantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans &#8220;Le\u00a0point du\u00a0mari&#8221; \u2013 ma nouvelle pr\u00e9f\u00e9r\u00e9e de la collection \u2013 Machado entrelace des l\u00e9gendes urbaines avec l&#8217;histoire d&#8217;une jeune femme dont le cou est encercl\u00e9 par un myst\u00e9rieux ruban vert. L&#8217;\u00e9rotisme dans cette histoire est \u00e9lectrisant et direct, mais impr\u00e9gn\u00e9 d&#8217;une tension inqui\u00e9tante : que se passe-t-il si son mari d\u00e9noue le ruban qu&#8217;il convoite tant ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;histoire nous confronte \u00e0 la r\u00e9alit\u00e9 effrayante que les corps des femmes sont souvent consid\u00e9r\u00e9s comme la propri\u00e9t\u00e9 des autres \u2013 m\u00eame dans les relations intimes. &#8220;Le\u00a0point du\u00a0mari&#8221; lui-m\u00eame fait r\u00e9f\u00e9rence \u00e0 un point de suture suppl\u00e9mentaire parfois donn\u00e9 par les m\u00e9decins apr\u00e8s l&#8217;accouchement, soi-disant pour resserrer le vagin pour le plaisir sexuel du mari.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-les-corps-comme-champs-de-bataille-et-jardins-de-plaisir-simultanement\">Les corps comme champs de bataille et jardins de plaisir simultan\u00e9ment<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Que pouvons-nous, en tant qu&#8217;auteur\u00b7e\u00b7s de litt\u00e9rature \u00e9rotique, apprendre de Machado ? Tellement de choses !<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Nous pouvons comprendre le corps comme un espace politique<\/strong>. L&#8217;\u0153uvre de Machado nous rappelle que nos corps ne sont jamais neutres. Ils sont des lieux o\u00f9 les structures de pouvoir, les pr\u00e9jug\u00e9s et les luttes de lib\u00e9ration se jouent. L&#8217;\u00e9rotisme peut et doit reconna\u00eetre cette dimension.<\/li>\n\n\n\n<li><strong>Nous pouvons jouer avec les genres litt\u00e9raires<\/strong>. Pourquoi la litt\u00e9rature \u00e9rotique doit-elle rester dans un seul tiroir ? Machado m\u00e9lange l&#8217;horreur, la science-fiction, la fantasy et les contes de f\u00e9es avec des repr\u00e9sentations sexuelles explicites. Ce m\u00e9lange nous permet d&#8217;aller au-del\u00e0 de la m\u00e9canique conventionnelle du &#8220;tab A dans slot B&#8221; et de plonger plut\u00f4t dans des couches plus profondes du d\u00e9sir.<\/li>\n\n\n\n<li><strong>Nous devons c\u00e9l\u00e9brer les exp\u00e9riences queer<\/strong>. Les personnages de Machado \u00e9voluent au-del\u00e0 des fronti\u00e8res h\u00e9t\u00e9ronormatives. Ils d\u00e9sirent de mani\u00e8re complexe, contradictoire et multiforme. En tant qu&#8217;\u00e9crivain\u00b7e\u00b7s, nous pouvons apprendre de cette complexit\u00e9 et cr\u00e9er une litt\u00e9rature \u00e9rotique qui refl\u00e8te la diversit\u00e9 de la sexualit\u00e9 et de l&#8217;identit\u00e9 humaines.<\/li>\n\n\n\n<li><strong>Nous pouvons explorer l&#8217;\u00e9tranget\u00e9 de nos corps<\/strong>. Les corps sont \u00e9tranges. Ils changent, ils nous surprennent, ils \u00e9chappent \u00e0 notre contr\u00f4le. Au lieu d&#8217;id\u00e9aliser des corps parfaits et lisses, nous pouvons explorer l&#8217;\u00e9tranget\u00e9 existentielle de l&#8217;incarnation.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-poesie-de-la-chair\">La po\u00e9sie de la chair<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La prose de Machado est audacieuse non seulement dans ses th\u00e8mes mais aussi dans son langage. Elle combine des images po\u00e9tiques avec des descriptions sexuelles brutes et directes. Ce contraste cr\u00e9e une tension \u00e9lectrisante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans &#8220;Inventaire\u00a0&#8220;, une narratrice \u00e9num\u00e8re ses rencontres sexuelles pendant qu&#8217;une peste d\u00e9cime le monde autour d&#8217;elle. La sobri\u00e9t\u00e9 clinique de l&#8217;\u00e9num\u00e9ration contraste avec l&#8217;intimit\u00e9 des actes d\u00e9crits et le d\u00e9cor apocalyptique. Une le\u00e7on pour nous toutes et tous : la litt\u00e9rature \u00e9rotique peut prosp\u00e9rer gr\u00e2ce aux contrastes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-liberation-de-l-ecriture-erotique\">La lib\u00e9ration de l&#8217;\u00e9criture \u00e9rotique<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ce qui m&#8217;enthousiasme le plus dans l&#8217;\u0153uvre de Machado : elle lib\u00e8re la litt\u00e9rature \u00e9rotique de ses entraves conventionnelles. Elle nous montre que l&#8217;\u00e9criture \u00e9rotique ne doit pas seulement servir l&#8217;excitation (bien qu&#8217;elle puisse certainement le faire aussi !), mais peut \u00e9galement \u00eatre un outil pour explorer des questions profondes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comment vivons-nous nos corps dans un monde qui veut les contr\u00f4ler ?<\/li>\n\n\n\n<li>Comment naviguons-nous dans le d\u00e9sir qui est parfois entrelac\u00e9 avec le danger ?<\/li>\n\n\n\n<li>Comment pouvons-nous nous appartenir dans une soci\u00e9t\u00e9 qui veut nous d\u00e9poss\u00e9der ?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Que tu \u00e9crives toi-m\u00eame de la litt\u00e9rature \u00e9rotique ou que tu aimes simplement la lire : l&#8217;\u0153uvre de Machado nous encourage \u00e0 \u00eatre plus audacieux\u00b7ses. Pas seulement dans ce que nous repr\u00e9sentons, mais aussi dans la fa\u00e7on dont nous le faisons.<\/p>\n\n\n\n<p class=\"has-background wp-block-paragraph\" style=\"background-color:#cbeac4\"><em>La prochaine fois que tu te retrouveras devant une page blanche, souviens-toi : ton histoire \u00e9rotique peut \u00eatre simultan\u00e9ment un film d&#8217;horreur, un manifeste politique et une chanson d&#8217;amour. Ose briser les fronti\u00e8res \u2013 tout comme le fait Carmen Maria Machado.<br>Et maintenant : quelles fronti\u00e8res vas-TU transcender dans ton prochain texte ?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As-tu d\u00e9j\u00e0 lu un livre qui t&#8217;excite et te fait frissonner en m\u00eame temps ? Un livre qui brouille les fronti\u00e8res de ton corps et te demande : Qu&#8217;est-ce qui est r\u00e9el ? Qu&#8217;est-ce qui est possible ? Et surtout : \u00c0 qui appartient vraiment ton corps ? Carmen Maria Machado, avec son recueil de &hellip; <a href=\"https:\/\/manther.de\/fr\/2025\/03\/carmen-maria-machado-quand-lerotisme-rencontre-lhorreur\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Carmen Maria Machado : Quand l&#8217;\u00e9rotisme rencontre l&#8217;horreur \u2013 Une r\u00e9volution pour la litt\u00e9rature \u00e9rotique<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":7020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"<a href=\"https:\/\/en.wikipedia.org\/wiki\/Carmen_Maria_Machado#\/media\/File:Carmen_Maria_Machado.jpg\">Carmen Maria Machado 2017<\/a>, <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\">CC BY-SA 4.0<\/a>","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-7019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erotika-schreiben"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["de","en","fr"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carmen Maria Machado : Quand l&#039;\u00e9rotisme rencontre l&#039;horreur \u2013 Une r\u00e9volution pour la litt\u00e9rature \u00e9rotique - manther<\/title>\n<meta name=\"description\" content=\"Comment la fusion r\u00e9volutionnaire entre horreur et \u00e9rotisme queer de Carmen Maria Machado transforme notre compr\u00e9hension des corps et du d\u00e9sir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carmen Maria Machado : Quand l&#039;\u00e9rotisme rencontre l&#039;horreur \u2013 Une r\u00e9volution pour la litt\u00e9rature \u00e9rotique - manther\" \/>\n<meta property=\"og:description\" content=\"Comment la fusion r\u00e9volutionnaire entre horreur et \u00e9rotisme queer de Carmen Maria Machado transforme notre compr\u00e9hension des corps et du d\u00e9sir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/\" \/>\n<meta property=\"og:site_name\" content=\"manther\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mantherhh\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/mantherhh\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-27T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/Carmen-Maria-Machado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"672\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sandra Manther\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Sandra_Manther\" \/>\n<meta name=\"twitter:site\" content=\"@Sandra_Manther\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Manther\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/\"},\"author\":{\"name\":\"Sandra Manther\",\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/5d0a51ad8607f193a3e54080c7286894\"},\"headline\":\"Carmen Maria Machado : Quand l&#8217;\u00e9rotisme rencontre l&#8217;horreur \u2013 Une r\u00e9volution pour la litt\u00e9rature \u00e9rotique\",\"datePublished\":\"2025-03-27T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/\"},\"wordCount\":2250,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/5d0a51ad8607f193a3e54080c7286894\"},\"image\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Carmen-Maria-Machado.jpg\",\"articleSection\":[\"\u00c9crire \u00e9rotique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/\",\"url\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/\",\"name\":\"Carmen Maria Machado : Quand l'\u00e9rotisme rencontre l'horreur \u2013 Une r\u00e9volution pour la litt\u00e9rature \u00e9rotique - manther\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Carmen-Maria-Machado.jpg\",\"datePublished\":\"2025-03-27T08:00:00+00:00\",\"description\":\"Comment la fusion r\u00e9volutionnaire entre horreur et \u00e9rotisme queer de Carmen Maria Machado transforme notre compr\u00e9hension des corps et du d\u00e9sir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/#primaryimage\",\"url\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Carmen-Maria-Machado.jpg\",\"contentUrl\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Carmen-Maria-Machado.jpg\",\"width\":672,\"height\":372,\"caption\":\"Machado in 2017\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manther.de\\\/2025\\\/03\\\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/manther.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carmen Maria Machado: Wenn Erotik auf Horror trifft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manther.de\\\/#website\",\"url\":\"https:\\\/\\\/manther.de\\\/\",\"name\":\"manther\",\"description\":\"le magazine de Creative Writing pour la litt\u00e9rature \u00e9rotique\",\"publisher\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/5d0a51ad8607f193a3e54080c7286894\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manther.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/5d0a51ad8607f193a3e54080c7286894\",\"name\":\"Sandra Manther\",\"logo\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"description\":\"Geboren 1981 in Krefeld. Studierte Mediendesign an der hdpk Berlin. Der Liebe wegen ging sie nach Hamburg, wo sie heute als Webdesgnerin in einer bekannten Werbeagentur arbeitet. Sie lebt mit ihrem Mann Marc und den Katzen Mandu und Tharsis in einem Haus im Westen der Stadt.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mantherhh\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/sandramanther\\\/\",\"https:\\\/\\\/x.com\\\/Sandra_Manther\",\"https:\\\/\\\/www.tumblr.com\\\/gamma-xi-delta\"],\"url\":\"https:\\\/\\\/manther.de\\\/fr\\\/author\\\/sandra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Carmen Maria Machado : Quand l'\u00e9rotisme rencontre l'horreur \u2013 Une r\u00e9volution pour la litt\u00e9rature \u00e9rotique - manther","description":"Comment la fusion r\u00e9volutionnaire entre horreur et \u00e9rotisme queer de Carmen Maria Machado transforme notre compr\u00e9hension des corps et du d\u00e9sir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/","og_locale":"fr_FR","og_type":"article","og_title":"Carmen Maria Machado : Quand l'\u00e9rotisme rencontre l'horreur \u2013 Une r\u00e9volution pour la litt\u00e9rature \u00e9rotique - manther","og_description":"Comment la fusion r\u00e9volutionnaire entre horreur et \u00e9rotisme queer de Carmen Maria Machado transforme notre compr\u00e9hension des corps et du d\u00e9sir.","og_url":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/","og_site_name":"manther","article_publisher":"https:\/\/www.facebook.com\/mantherhh\/","article_author":"https:\/\/www.facebook.com\/mantherhh\/","article_published_time":"2025-03-27T08:00:00+00:00","og_image":[{"width":672,"height":372,"url":"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/Carmen-Maria-Machado.jpg","type":"image\/jpeg"}],"author":"Sandra Manther","twitter_card":"summary_large_image","twitter_creator":"@Sandra_Manther","twitter_site":"@Sandra_Manther","twitter_misc":{"\u00c9crit par":"Sandra Manther","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/#article","isPartOf":{"@id":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/"},"author":{"name":"Sandra Manther","@id":"https:\/\/manther.de\/#\/schema\/person\/5d0a51ad8607f193a3e54080c7286894"},"headline":"Carmen Maria Machado : Quand l&#8217;\u00e9rotisme rencontre l&#8217;horreur \u2013 Une r\u00e9volution pour la litt\u00e9rature \u00e9rotique","datePublished":"2025-03-27T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/"},"wordCount":2250,"commentCount":0,"publisher":{"@id":"https:\/\/manther.de\/#\/schema\/person\/5d0a51ad8607f193a3e54080c7286894"},"image":{"@id":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/#primaryimage"},"thumbnailUrl":"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/Carmen-Maria-Machado.jpg","articleSection":["\u00c9crire \u00e9rotique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/","url":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/","name":"Carmen Maria Machado : Quand l'\u00e9rotisme rencontre l'horreur \u2013 Une r\u00e9volution pour la litt\u00e9rature \u00e9rotique - manther","isPartOf":{"@id":"https:\/\/manther.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/#primaryimage"},"image":{"@id":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/#primaryimage"},"thumbnailUrl":"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/Carmen-Maria-Machado.jpg","datePublished":"2025-03-27T08:00:00+00:00","description":"Comment la fusion r\u00e9volutionnaire entre horreur et \u00e9rotisme queer de Carmen Maria Machado transforme notre compr\u00e9hension des corps et du d\u00e9sir.","breadcrumb":{"@id":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/#primaryimage","url":"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/Carmen-Maria-Machado.jpg","contentUrl":"https:\/\/manther.de\/wp-content\/uploads\/2025\/03\/Carmen-Maria-Machado.jpg","width":672,"height":372,"caption":"Machado in 2017"},{"@type":"BreadcrumbList","@id":"https:\/\/manther.de\/2025\/03\/carmen-maria-machado-wenn-erotik-auf-horror-trifft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/manther.de\/"},{"@type":"ListItem","position":2,"name":"Carmen Maria Machado: Wenn Erotik auf Horror trifft"}]},{"@type":"WebSite","@id":"https:\/\/manther.de\/#website","url":"https:\/\/manther.de\/","name":"manther","description":"le magazine de Creative Writing pour la litt\u00e9rature \u00e9rotique","publisher":{"@id":"https:\/\/manther.de\/#\/schema\/person\/5d0a51ad8607f193a3e54080c7286894"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manther.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/manther.de\/#\/schema\/person\/5d0a51ad8607f193a3e54080c7286894","name":"Sandra Manther","logo":{"@id":"https:\/\/manther.de\/#\/schema\/person\/image\/"},"description":"Geboren 1981 in Krefeld. Studierte Mediendesign an der hdpk Berlin. Der Liebe wegen ging sie nach Hamburg, wo sie heute als Webdesgnerin in einer bekannten Werbeagentur arbeitet. Sie lebt mit ihrem Mann Marc und den Katzen Mandu und Tharsis in einem Haus im Westen der Stadt.","sameAs":["https:\/\/www.facebook.com\/mantherhh\/","https:\/\/www.pinterest.de\/sandramanther\/","https:\/\/x.com\/Sandra_Manther","https:\/\/www.tumblr.com\/gamma-xi-delta"],"url":"https:\/\/manther.de\/fr\/author\/sandra\/"}]}},"_links":{"self":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts\/7019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/comments?post=7019"}],"version-history":[{"count":4,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts\/7019\/revisions"}],"predecessor-version":[{"id":7030,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts\/7019\/revisions\/7030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/media\/7020"}],"wp:attachment":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/media?parent=7019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/categories?post=7019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/tags?post=7019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}