{"id":4858,"date":"2023-10-07T10:00:00","date_gmt":"2023-10-07T08:00:00","guid":{"rendered":"https:\/\/manther.de\/?p=4858"},"modified":"2023-10-25T17:33:32","modified_gmt":"2023-10-25T15:33:32","slug":"die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik","status":"publish","type":"post","link":"https:\/\/manther.de\/fr\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/","title":{"rendered":"La beaut\u00e9 de la diversit\u00e9 : les petits seins dans la litt\u00e9rature"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Quand il s&#8217;agit de litt\u00e9rature \u00e9rotique, la repr\u00e9sentation des personnages f\u00e9minins a une grande influence sur la perception de la beaut\u00e9 et de la sexualit\u00e9 par le lecteur. Les femmes aux seins plus gros sont traditionnellement au centre de l&#8217;int\u00e9r\u00eat, mais qu&#8217;en est-il des femmes aux seins plus petits ? Comment sont-elles repr\u00e9sent\u00e9es et quel est l&#8217;impact de ces repr\u00e9sentations sur la perception de la beaut\u00e9 et de la sexualit\u00e9 des lecteurs ? Dans cet article de blog, nous allons examiner comment les petits seins sont repr\u00e9sent\u00e9s dans la litt\u00e9rature \u00e9rotique et quel est l&#8217;impact de ces repr\u00e9sentations sur les lecteurs\/trices.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Repr\u00e9sentations n\u00e9gatives des petits seins<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Malheureusement, les petits seins sont souvent utilis\u00e9s de mani\u00e8re n\u00e9gative dans la litt\u00e9rature \u00e9rotique. Les auteurs les utilisent souvent pour repr\u00e9senter des personnages ind\u00e9sirables ou peu attrayants. Certains auteurs utilisent les petits seins pour montrer qu&#8217;un personnage manque de f\u00e9minit\u00e9 ou qu&#8217;il n&#8217;est pas assez &#8220;f\u00e9minin&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;un des exemples les plus connus \u00e0 ce sujet est &#8220;Orgueil et Pr\u00e9jug\u00e9s&#8221; de <strong>Jane Austen<\/strong>. L&#8217;auteur s&#8217;efforce de d\u00e9crire clairement le personnage d&#8217;Elizabeth Bennet. Son manque de courbes et ses petits seins sont mis en avant, ce qui est pr\u00e9sent\u00e9 comme des caract\u00e9ristiques d\u00e9savantageuses aux yeux de ses admirateurs masculins. Austen illustre ainsi les d\u00e9fis auxquels les femmes qui ne correspondent pas \u00e0 un certain standard de beaut\u00e9 doivent faire face dans leur vie quotidienne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un autre exemple de ce th\u00e8me se trouve dans la s\u00e9rie de <strong>George R. R. Martin<\/strong> &#8220;Le chant de la glace et du feu&#8221;. Martin a toujours \u00e9t\u00e9 connu pour d\u00e9crire ses personnages en d\u00e9tail. Le personnage de Brienne de Tarth est connu pour sa taille et son manque d&#8217;attributs f\u00e9minins, y compris de petits seins, dont les autres personnages se moquent souvent. L&#8217;approche de Martin r\u00e9v\u00e8le le sexisme dans ce monde fictif et met en \u00e9vidence \u00e0 quel point les femmes en souffrent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le roman de <strong>Jacqueline Susann<\/strong> &#8220;La vall\u00e9e des poup\u00e9es&#8221;, le personnage d&#8217;Anne Welles est pr\u00e9sent\u00e9 comme moins attrayant parce qu&#8217;elle a des seins plus petits. La taille de ses seins est mentionn\u00e9e plusieurs fois dans le livre et est associ\u00e9e \u00e0 des connotations n\u00e9gatives. Et m\u00eame Clay, le personnage principal du roman de <strong>Bret Easton Ellis <\/strong>&#8220;Unter Null&#8221;, commente souvent de mani\u00e8re n\u00e9gative l&#8217;apparence des femmes de sa vie, y compris la taille de leur poitrine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette repr\u00e9sentation n\u00e9gative peut \u00eatre particuli\u00e8rement probl\u00e9matique, car elle renforce les st\u00e9r\u00e9otypes n\u00e9gatifs sur le corps et l&#8217;estime de soi des femmes. C&#8217;est pourquoi les auteurs doivent tenir compte de l&#8217;impact de telles repr\u00e9sentations, en particulier chez les jeunes lecteurs qui peuvent influencer ces perceptions.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Descriptions positives de petits seins<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 la connotation n\u00e9gative, le march\u00e9 litt\u00e9raire a toujours abord\u00e9 les petits seins. Souvent, les petits seins sont associ\u00e9s aux femmes plus jeunes, car ils sont typiquement moins d\u00e9velopp\u00e9s pendant l&#8217;adolescence que chez les femmes plus \u00e2g\u00e9es. En cons\u00e9quence, elles ont la r\u00e9putation de para\u00eetre jeunes m\u00eame \u00e0 un \u00e2ge avanc\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans &#8220;L&#8217;insoutenable l\u00e9g\u00e8ret\u00e9 de l&#8217;\u00eatre&#8221; de <strong>Milan Kundera<\/strong>, les personnages sont repr\u00e9sent\u00e9s dans toutes leurs particularit\u00e9s physiques et leurs incertitudes. Tomas, le protagoniste du roman, est un coureur de jupons et a de nombreuses aventures, mais il est fascin\u00e9 par les &#8220;petits seins fermes&#8221; de Teresa, une \u00e9tudiante. Il les d\u00e9crit comme &#8220;d\u00e9licats et sensibles&#8221; et dit qu&#8217;ils lui rappellent &#8220;la poitrine de sa m\u00e8re&#8221;. Les petits seins de Teresa ne sont pas consid\u00e9r\u00e9s comme un d\u00e9faut, mais comme une partie de son individualit\u00e9 et de sa beaut\u00e9 personnelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans &#8220;L&#8217;amant&#8221; de <strong>Marguerite Duras<\/strong>, la protagoniste adolescente est \u00e9galement d\u00e9crite comme mince et gracieuse, y compris ses petits seins. La description souligne la d\u00e9licatesse et la gr\u00e2ce de son corps, sans la sexualiser de mani\u00e8re r\u00e9ductionniste.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Normalisation des petits seins<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 les pr\u00e9jug\u00e9s auxquels les petits seins sont confront\u00e9s dans la litt\u00e9rature, certains auteurs ont essay\u00e9 de repr\u00e9senter les petits seins dans leurs \u0153uvres d&#8217;une mani\u00e8re qui c\u00e9l\u00e8bre leur caract\u00e8re unique et leur beaut\u00e9 et qui montre qu&#8217;ils sont aussi attirants que des seins plus gros. De cette mani\u00e8re, ils encouragent une image corporelle positive et remettent en question les standards de beaut\u00e9 traditionnels qui ont maintenu des st\u00e9r\u00e9otypes n\u00e9gatifs sur le corps des femmes. Une telle repr\u00e9sentation peut \u00eatre particuli\u00e8rement encourageante pour les femmes qui ne se sentent pas en s\u00e9curit\u00e9 \u00e0 cause de leur forme corporelle.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un appel \u00e0 plus de diversit\u00e9 dans les repr\u00e9sentations<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Au fur et \u00e0 mesure que la litt\u00e9rature \u00e9volue, l&#8217;appel \u00e0 une repr\u00e9sentation plus vari\u00e9e de diff\u00e9rents types de corps dans la litt\u00e9rature \u00e9rotique se fait de plus en plus fort. Les auteurs devraient donc penser \u00e0 inclure plus de types de corps diff\u00e9rents dans leur travail et \u00e0 d\u00e9crire la beaut\u00e9 des petits seins de mani\u00e8re aussi sensuelle qu&#8217;ils le font pour les plus gros. De cette mani\u00e8re, ils peuvent contribuer \u00e0 briser les normes de beaut\u00e9 traditionnelles et \u00e0 promouvoir une soci\u00e9t\u00e9 plus juste et plus inclusive. De telles repr\u00e9sentations peuvent \u00e9galement aider les jeunes lecteurs \u00e0 appr\u00e9cier et \u00e0 accepter leur corps, quelle que soit sa taille.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>La repr\u00e9sentation des petits seins dans la litt\u00e9rature \u00e9rotique a une grande influence sur la perception de la beaut\u00e9 et de la sexualit\u00e9 par les lecteurs\/trices. Alors que certains auteurs ont normalis\u00e9 les petits seins et remis en question les standards de beaut\u00e9 traditionnels, d&#8217;autres ont maintenu des st\u00e9r\u00e9otypes n\u00e9gatifs ou f\u00e9tichis\u00e9 les petits seins. Les auteurs devraient prendre en compte l&#8217;impact de leur repr\u00e9sentation des petites poitrines sur leur lectorat et la soci\u00e9t\u00e9. Une plus grande diversit\u00e9 dans la litt\u00e9rature peut contribuer \u00e0 promouvoir la conscience corporelle et \u00e0 cr\u00e9er une soci\u00e9t\u00e9 qui accepte, tout en \u00e9liminant les st\u00e9r\u00e9otypes nuisibles.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand il s&#8217;agit de litt\u00e9rature \u00e9rotique, la repr\u00e9sentation des personnages f\u00e9minins a une grande influence sur la perception de la beaut\u00e9 et de la sexualit\u00e9 par le lecteur. Les femmes aux seins plus gros sont traditionnellement au centre de l&#8217;int\u00e9r\u00eat, mais qu&#8217;en est-il des femmes aux seins plus petits ? Comment sont-elles repr\u00e9sent\u00e9es et quel &hellip; <a href=\"https:\/\/manther.de\/fr\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">La beaut\u00e9 de la diversit\u00e9 : les petits seins dans la litt\u00e9rature<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":4899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"&copy; Sandra Manther","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-4858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erotika-schreiben"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["de","en","fr"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La beaut\u00e9 de la diversit\u00e9 : les petits seins dans la litt\u00e9rature - manther<\/title>\n<meta name=\"description\" content=\"Dans ce billet de blog, nous allons examiner la repr\u00e9sentation des petits seins dans la litt\u00e9rature et leur fonction dans le texte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La beaut\u00e9 de la diversit\u00e9 : les petits seins dans la litt\u00e9rature - manther\" \/>\n<meta property=\"og:description\" content=\"Dans ce billet de blog, nous allons examiner la repr\u00e9sentation des petits seins dans la litt\u00e9rature et leur fonction dans le texte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/\" \/>\n<meta property=\"og:site_name\" content=\"manther\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mantherhh\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-07T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T15:33:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/manther.de\/wp-content\/uploads\/2023\/10\/a-cups.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"672\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ennka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sandra_Manther\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ennka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/\"},\"author\":{\"name\":\"Ennka\",\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/f1e1c8775b15c7ee7a684f857868d1f1\"},\"headline\":\"La beaut\u00e9 de la diversit\u00e9 : les petits seins dans la litt\u00e9rature\",\"datePublished\":\"2023-10-07T08:00:00+00:00\",\"dateModified\":\"2023-10-25T15:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/\"},\"wordCount\":2806,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/5d0a51ad8607f193a3e54080c7286894\"},\"image\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/a-cups.jpg\",\"articleSection\":[\"\u00c9crire \u00e9rotique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/\",\"url\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/\",\"name\":\"La beaut\u00e9 de la diversit\u00e9 : les petits seins dans la litt\u00e9rature - manther\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/a-cups.jpg\",\"datePublished\":\"2023-10-07T08:00:00+00:00\",\"dateModified\":\"2023-10-25T15:33:32+00:00\",\"description\":\"In diesem Blogbeitrag untersuchen wir, wie kleine Br\u00fcste in der erotischen Literatur dargestellt werden und welche Auswirkung diese Darstellungen haben.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/a-cups.jpg\",\"contentUrl\":\"https:\\\/\\\/manther.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/a-cups.jpg\",\"width\":672,\"height\":372},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manther.de\\\/2023\\\/10\\\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/manther.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Sch\u00f6nheit der Vielfalt: Kleine Br\u00fcste in der Literatur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manther.de\\\/#website\",\"url\":\"https:\\\/\\\/manther.de\\\/\",\"name\":\"manther\",\"description\":\"le magazine de Creative Writing pour la litt\u00e9rature \u00e9rotique\",\"publisher\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/5d0a51ad8607f193a3e54080c7286894\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manther.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/5d0a51ad8607f193a3e54080c7286894\",\"name\":\"Sandra Manther\",\"logo\":{\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"description\":\"Geboren 1981 in Krefeld. Studierte Mediendesign an der hdpk Berlin. Der Liebe wegen ging sie nach Hamburg, wo sie heute als Webdesgnerin in einer bekannten Werbeagentur arbeitet. Sie lebt mit ihrem Mann Marc und den Katzen Mandu und Tharsis in einem Haus im Westen der Stadt.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mantherhh\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/sandramanther\\\/\",\"https:\\\/\\\/x.com\\\/Sandra_Manther\",\"https:\\\/\\\/www.tumblr.com\\\/gamma-xi-delta\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/manther.de\\\/#\\\/schema\\\/person\\\/f1e1c8775b15c7ee7a684f857868d1f1\",\"name\":\"Ennka\",\"sameAs\":[\"http:\\\/\\\/www.norbert-krueger.com\"],\"url\":\"https:\\\/\\\/manther.de\\\/fr\\\/author\\\/ennka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La beaut\u00e9 de la diversit\u00e9 : les petits seins dans la litt\u00e9rature - manther","description":"Dans ce billet de blog, nous allons examiner la repr\u00e9sentation des petits seins dans la litt\u00e9rature et leur fonction dans le texte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/","og_locale":"fr_FR","og_type":"article","og_title":"La beaut\u00e9 de la diversit\u00e9 : les petits seins dans la litt\u00e9rature - manther","og_description":"Dans ce billet de blog, nous allons examiner la repr\u00e9sentation des petits seins dans la litt\u00e9rature et leur fonction dans le texte.","og_url":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/","og_site_name":"manther","article_publisher":"https:\/\/www.facebook.com\/mantherhh\/","article_published_time":"2023-10-07T08:00:00+00:00","article_modified_time":"2023-10-25T15:33:32+00:00","og_image":[{"width":672,"height":372,"url":"https:\/\/manther.de\/wp-content\/uploads\/2023\/10\/a-cups.jpg","type":"image\/jpeg"}],"author":"Ennka","twitter_card":"summary_large_image","twitter_site":"@Sandra_Manther","twitter_misc":{"\u00c9crit par":"Ennka","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/#article","isPartOf":{"@id":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/"},"author":{"name":"Ennka","@id":"https:\/\/manther.de\/#\/schema\/person\/f1e1c8775b15c7ee7a684f857868d1f1"},"headline":"La beaut\u00e9 de la diversit\u00e9 : les petits seins dans la litt\u00e9rature","datePublished":"2023-10-07T08:00:00+00:00","dateModified":"2023-10-25T15:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/"},"wordCount":2806,"commentCount":0,"publisher":{"@id":"https:\/\/manther.de\/#\/schema\/person\/5d0a51ad8607f193a3e54080c7286894"},"image":{"@id":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/#primaryimage"},"thumbnailUrl":"https:\/\/manther.de\/wp-content\/uploads\/2023\/10\/a-cups.jpg","articleSection":["\u00c9crire \u00e9rotique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/","url":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/","name":"La beaut\u00e9 de la diversit\u00e9 : les petits seins dans la litt\u00e9rature - manther","isPartOf":{"@id":"https:\/\/manther.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/#primaryimage"},"image":{"@id":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/#primaryimage"},"thumbnailUrl":"https:\/\/manther.de\/wp-content\/uploads\/2023\/10\/a-cups.jpg","datePublished":"2023-10-07T08:00:00+00:00","dateModified":"2023-10-25T15:33:32+00:00","description":"In diesem Blogbeitrag untersuchen wir, wie kleine Br\u00fcste in der erotischen Literatur dargestellt werden und welche Auswirkung diese Darstellungen haben.","breadcrumb":{"@id":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/#primaryimage","url":"https:\/\/manther.de\/wp-content\/uploads\/2023\/10\/a-cups.jpg","contentUrl":"https:\/\/manther.de\/wp-content\/uploads\/2023\/10\/a-cups.jpg","width":672,"height":372},{"@type":"BreadcrumbList","@id":"https:\/\/manther.de\/2023\/10\/die-darstellung-kleiner-brueste-in-der-erotischen-literatur-auswirkungen-auf-schoenheit-und-erotik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/manther.de\/"},{"@type":"ListItem","position":2,"name":"Die Sch\u00f6nheit der Vielfalt: Kleine Br\u00fcste in der Literatur"}]},{"@type":"WebSite","@id":"https:\/\/manther.de\/#website","url":"https:\/\/manther.de\/","name":"manther","description":"le magazine de Creative Writing pour la litt\u00e9rature \u00e9rotique","publisher":{"@id":"https:\/\/manther.de\/#\/schema\/person\/5d0a51ad8607f193a3e54080c7286894"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manther.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/manther.de\/#\/schema\/person\/5d0a51ad8607f193a3e54080c7286894","name":"Sandra Manther","logo":{"@id":"https:\/\/manther.de\/#\/schema\/person\/image\/"},"description":"Geboren 1981 in Krefeld. Studierte Mediendesign an der hdpk Berlin. Der Liebe wegen ging sie nach Hamburg, wo sie heute als Webdesgnerin in einer bekannten Werbeagentur arbeitet. Sie lebt mit ihrem Mann Marc und den Katzen Mandu und Tharsis in einem Haus im Westen der Stadt.","sameAs":["https:\/\/www.facebook.com\/mantherhh\/","https:\/\/www.pinterest.de\/sandramanther\/","https:\/\/x.com\/Sandra_Manther","https:\/\/www.tumblr.com\/gamma-xi-delta"]},{"@type":"Person","@id":"https:\/\/manther.de\/#\/schema\/person\/f1e1c8775b15c7ee7a684f857868d1f1","name":"Ennka","sameAs":["http:\/\/www.norbert-krueger.com"],"url":"https:\/\/manther.de\/fr\/author\/ennka\/"}]}},"_links":{"self":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts\/4858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/comments?post=4858"}],"version-history":[{"count":11,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts\/4858\/revisions"}],"predecessor-version":[{"id":5035,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/posts\/4858\/revisions\/5035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/media\/4899"}],"wp:attachment":[{"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/media?parent=4858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/categories?post=4858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manther.de\/fr\/wp-json\/wp\/v2\/tags?post=4858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}